{"id":7051,"date":"2020-07-02T19:19:41","date_gmt":"2020-07-02T17:19:41","guid":{"rendered":"https:\/\/plantbezorgd.s01.klik3.dev\/algemeen\/tuinkalender-januari\/"},"modified":"2023-07-07T21:25:34","modified_gmt":"2023-07-07T19:25:34","slug":"gartenkalender-januar","status":"publish","type":"post","link":"https:\/\/plantbezorgd.nl\/de\/tuinonderhoud\/tuinkalender-januari\/","title":{"rendered":"Gartenkalender Januar"},"content":{"rendered":"<p><strong><img decoding=\"async\" src=\"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/07\/1.-Bevroren-gras_januari_tuinkalender.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/strong><\/p>\n<h3><strong>Gartenarbeiten im Januar<\/strong><\/h3>\n<p>Im Januar wachsen nur wenige Pflanzen. Der Garten ruht. Dieser Monat eignet sich gut, um alles im Garten zu \u00fcberpr\u00fcfen, Z\u00e4une zu reparieren und Pl\u00e4ne f\u00fcr den Fr\u00fchling zu schmieden. Hat es geschneit? Lassen Sie den Schnee einfach liegen; er isoliert die Pflanzen hervorragend.<\/p>\n<h4><strong>Pflanzen Januar <\/strong><\/h4>\n<ul>\n<li>Wenn es nicht friert und der Boden nicht gefroren ist, k\u00f6nnen Sie Pflanzen, Str\u00e4ucher, B\u00e4ume und Hecken pflanzen.<\/li>\n<li>In Pflanzgef\u00e4\u00dfen kann man bunte Veilchen pflanzen und <a href=\"https:\/\/plantbezorgd.nl\/de\/produkt-kategorie\/heidekrautpflanzen-2\/\">Winterheide<\/a> Pflanzen. Vergessen Sie nicht, sie regelm\u00e4\u00dfig zu gie\u00dfen.<\/li>\n<li>M\u00f6chten Sie Ihren Garten umgestalten und neue Pflanzen und B\u00e4ume setzen? Der Januar ist der ideale Monat, um einen Plan f\u00fcr die Gartengestaltung zu erstellen, gegebenenfalls in Absprache mit einem Landschaftsg\u00e4rtner oder Gartenarchitekten. <a href=\"https:\/\/plantbezorgd.nl\/de\/produkt-kategorie\/alle-gartenpflanzen\/\">Gartenpflanzen<\/a>, <a href=\"https:\/\/plantbezorgd.nl\/de\/produkt-kategorie\/alle-heckenpflanzen-2\/\">Hecken<\/a> und <a href=\"https:\/\/plantbezorgd.nl\/de\/produkt-kategorie\/alle-straucher-2\/\">Str\u00e4ucher<\/a> Bestellen Sie einfach und bequem bei PlantBezorgd, inklusive Lieferung.<strong style=\"font-size: 16px;\">\u00a0<\/strong><\/li>\n<\/ul>\n<h4><strong>R\u00fcckschnitt im Januar <\/strong><\/h4>\n<ul>\n<li>Der Januar eignet sich gut zum Schneiden von Obstb\u00e4umen, Spalierb\u00e4umen, Str\u00e4uchern, Laubstr\u00e4uchern und anderen Pflanzen sowie zum Entfernen abgestorbener \u00c4ste. Achten Sie darauf, dass es nicht friert.<\/li>\n<li>Warten Sie bis zum Sommer, um Fr\u00fchlingsbl\u00fcher wie Birken, Ahornb\u00e4ume und Nussb\u00e4ume zu beschneiden.<\/li>\n<li>Weinreben k\u00f6nnen sp\u00e4testens bis Mitte Januar geschnitten werden. Danach setzt der Saftfluss ein, und die Rebe kann nach dem Schnitt absterben.<\/li>\n<\/ul>\n<h4><strong>Rasen Januar <\/strong><\/h4>\n<ul>\n<li>Ihr Rasen ben\u00f6tigt im Januar wenig Pflege. Sofern das Gras nicht gefroren ist, k\u00f6nnen Sie eine Kalkschicht auf dem Rasen verteilen.<\/li>\n<li>Betreten Sie den Rasen nicht, wenn er gefroren ist, da dies zu gelben und braunen Brandflecken f\u00fchren kann.<\/li>\n<\/ul>\n<h4><strong>Gem\u00fcsegarten Januar <\/strong><\/h4>\n<ul>\n<li>Im Januar ruht der Gem\u00fcsegarten. Man kann noch nichts ins Freiland s\u00e4en. In einer beheizten Garage oder einem Gew\u00e4chshaus ist dies jedoch m\u00f6glich.<\/li>\n<li>Erstellen Sie einen Aussaatplan f\u00fcr das Fr\u00fchjahr.<\/li>\n<\/ul>\n<h4><strong>Teich Januar <\/strong><\/h4>\n<ul>\n<li>Bei Wassertemperaturen unter sechs Grad m\u00fcssen Fische nicht gef\u00fcttert werden.<\/li>\n<li>Ist der Teich zugefroren, bohren oder s\u00e4gen Sie vorsichtig (nicht hacken!) ein Loch ins Eis. So bleibt der Sauerstoffgehalt im Wasser erhalten. Alternativ k\u00f6nnen Sie auch eine Luftpumpe neben dem Teich aufstellen, um das Wasser in Bewegung zu halten.<\/li>\n<\/ul>\n<h4><strong>Noch mehr Tipps zur Gartenpflege im Januar?<\/strong><\/h4>\n<p>Stellen Sie Ihre Frage unten oder dann <a href=\"https:\/\/plantbezorgd.nl\/de\/kontakt-2\/\">Kontakt<\/a> Reden wir mit Bart von PlantBezorgd.<\/p>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/plantbezorgd.nl\/de\/allgemein-2\/gartenkalender\/\">Vollst\u00e4ndiger Gartenkalender<\/a><\/h1>","protected":false},"excerpt":{"rendered":"<p>Tuinklussen januari In januari groeien nog maar weinig planten. De tuin is in winterslaap. Deze maand is een goede tijd om alles in de tuin eens na te lopen, schuttingen te repareren en plannen voor het voorjaar te maken. Is er sneeuw gevallen? Lekker laten liggen, sneeuw zorgt voor uitstekende isolatie van de planten. Planten [&hellip;]<\/p>","protected":false},"author":1,"featured_media":7053,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":28,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-7051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tuinonderhoud"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tuinkalender januari - PlantBezorgd<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plantbezorgd.nl\/de\/gartenpflege\/gartenkalender-januar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tuinkalender januari - PlantBezorgd\" \/>\n<meta property=\"og:description\" content=\"Tuinklussen januari In januari groeien nog maar weinig planten. De tuin is in winterslaap. Deze maand is een goede tijd om alles in de tuin eens na te lopen, schuttingen te repareren en plannen voor het voorjaar te maken. Is er sneeuw gevallen? Lekker laten liggen, sneeuw zorgt voor uitstekende isolatie van de planten. Planten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plantbezorgd.nl\/de\/gartenpflege\/gartenkalender-januar\/\" \/>\n<meta property=\"og:site_name\" content=\"PlantBezorgd\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-02T17:19:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-07T19:25:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.plantbezorgd.nl\/wp-content\/uploads\/2023\/07\/1.-Bevroren-gras_januari_tuinkalender-scaled-1.jpg?strip=all&lossy=1&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1386\" \/>\n\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webworx\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"webworx\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/\"},\"author\":{\"name\":\"webworx\",\"@id\":\"https:\/\/plantbezorgd.nl\/#\/schema\/person\/295e2eea08cf875acfbabd13295c5975\"},\"headline\":\"Tuinkalender januari\",\"datePublished\":\"2020-07-02T17:19:41+00:00\",\"dateModified\":\"2023-07-07T19:25:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/\"},\"wordCount\":352,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/plantbezorgd.nl\/#organization\"},\"image\":{\"@id\":\"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/07\/1.-Bevroren-gras_januari_tuinkalender-scaled-1.jpg\",\"articleSection\":[\"Tuinonderhoud\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/\",\"url\":\"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/\",\"name\":\"Tuinkalender januari - PlantBezorgd\",\"isPartOf\":{\"@id\":\"https:\/\/plantbezorgd.nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/07\/1.-Bevroren-gras_januari_tuinkalender-scaled-1.jpg\",\"datePublished\":\"2020-07-02T17:19:41+00:00\",\"dateModified\":\"2023-07-07T19:25:34+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#primaryimage\",\"url\":\"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/07\/1.-Bevroren-gras_januari_tuinkalender-scaled-1.jpg\",\"contentUrl\":\"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/07\/1.-Bevroren-gras_januari_tuinkalender-scaled-1.jpg\",\"width\":1386,\"height\":924},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/plantbezorgd.nl\/#website\",\"url\":\"https:\/\/plantbezorgd.nl\/\",\"name\":\"PlantBezorgd\",\"description\":\"Betaalbare kwaliteitsplanten thuisbezorgd!\",\"publisher\":{\"@id\":\"https:\/\/plantbezorgd.nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/plantbezorgd.nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/plantbezorgd.nl\/#organization\",\"name\":\"PlantBezorgd\",\"url\":\"https:\/\/plantbezorgd.nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/plantbezorgd.nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/05\/Logo.svg\",\"contentUrl\":\"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/05\/Logo.svg\",\"caption\":\"PlantBezorgd\"},\"image\":{\"@id\":\"https:\/\/plantbezorgd.nl\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/plantbezorgd.nl\/#\/schema\/person\/295e2eea08cf875acfbabd13295c5975\",\"name\":\"webworx\",\"url\":\"https:\/\/plantbezorgd.nl\/de\/author\/webworx\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gartenkalender Januar - PlantBezorgd","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plantbezorgd.nl\/de\/gartenpflege\/gartenkalender-januar\/","og_locale":"de_DE","og_type":"article","og_title":"Tuinkalender januari - PlantBezorgd","og_description":"Tuinklussen januari In januari groeien nog maar weinig planten. De tuin is in winterslaap. Deze maand is een goede tijd om alles in de tuin eens na te lopen, schuttingen te repareren en plannen voor het voorjaar te maken. Is er sneeuw gevallen? Lekker laten liggen, sneeuw zorgt voor uitstekende isolatie van de planten. Planten [&hellip;]","og_url":"https:\/\/plantbezorgd.nl\/de\/gartenpflege\/gartenkalender-januar\/","og_site_name":"PlantBezorgd","article_published_time":"2020-07-02T17:19:41+00:00","article_modified_time":"2023-07-07T19:25:34+00:00","og_image":[{"width":1386,"height":924,"url":"https:\/\/cdn.plantbezorgd.nl\/wp-content\/uploads\/2023\/07\/1.-Bevroren-gras_januari_tuinkalender-scaled-1.jpg?strip=all&lossy=1&ssl=1","type":"image\/jpeg"}],"author":"webworx","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"webworx","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#article","isPartOf":{"@id":"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/"},"author":{"name":"webworx","@id":"https:\/\/plantbezorgd.nl\/#\/schema\/person\/295e2eea08cf875acfbabd13295c5975"},"headline":"Tuinkalender januari","datePublished":"2020-07-02T17:19:41+00:00","dateModified":"2023-07-07T19:25:34+00:00","mainEntityOfPage":{"@id":"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/"},"wordCount":352,"commentCount":0,"publisher":{"@id":"https:\/\/plantbezorgd.nl\/#organization"},"image":{"@id":"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#primaryimage"},"thumbnailUrl":"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/07\/1.-Bevroren-gras_januari_tuinkalender-scaled-1.jpg","articleSection":["Tuinonderhoud"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/","url":"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/","name":"Gartenkalender Januar - PlantBezorgd","isPartOf":{"@id":"https:\/\/plantbezorgd.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#primaryimage"},"image":{"@id":"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#primaryimage"},"thumbnailUrl":"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/07\/1.-Bevroren-gras_januari_tuinkalender-scaled-1.jpg","datePublished":"2020-07-02T17:19:41+00:00","dateModified":"2023-07-07T19:25:34+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/plantbezorgd.nl\/tuinonderhoud\/tuinkalender-januari\/#primaryimage","url":"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/07\/1.-Bevroren-gras_januari_tuinkalender-scaled-1.jpg","contentUrl":"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/07\/1.-Bevroren-gras_januari_tuinkalender-scaled-1.jpg","width":1386,"height":924},{"@type":"WebSite","@id":"https:\/\/plantbezorgd.nl\/#website","url":"https:\/\/plantbezorgd.nl\/","name":"PflanzenGeliefert","description":"Erschwingliche Qualit\u00e4tspflanzen direkt zu Ihnen nach Hause geliefert!","publisher":{"@id":"https:\/\/plantbezorgd.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plantbezorgd.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/plantbezorgd.nl\/#organization","name":"PflanzenGeliefert","url":"https:\/\/plantbezorgd.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/plantbezorgd.nl\/#\/schema\/logo\/image\/","url":"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/05\/Logo.svg","contentUrl":"https:\/\/plantbezorgd.nl\/wp-content\/uploads\/2023\/05\/Logo.svg","caption":"PlantBezorgd"},"image":{"@id":"https:\/\/plantbezorgd.nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/plantbezorgd.nl\/#\/schema\/person\/295e2eea08cf875acfbabd13295c5975","name":"webworx","url":"https:\/\/plantbezorgd.nl\/de\/author\/webworx\/"}]}},"_links":{"self":[{"href":"https:\/\/plantbezorgd.nl\/de\/wp-json\/wp\/v2\/posts\/7051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plantbezorgd.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plantbezorgd.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plantbezorgd.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/plantbezorgd.nl\/de\/wp-json\/wp\/v2\/comments?post=7051"}],"version-history":[{"count":0,"href":"https:\/\/plantbezorgd.nl\/de\/wp-json\/wp\/v2\/posts\/7051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plantbezorgd.nl\/de\/wp-json\/wp\/v2\/media\/7053"}],"wp:attachment":[{"href":"https:\/\/plantbezorgd.nl\/de\/wp-json\/wp\/v2\/media?parent=7051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plantbezorgd.nl\/de\/wp-json\/wp\/v2\/categories?post=7051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plantbezorgd.nl\/de\/wp-json\/wp\/v2\/tags?post=7051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}